{"id":1945,"date":"2025-04-21T18:33:54","date_gmt":"2025-04-21T18:33:54","guid":{"rendered":"https:\/\/newtak.ch\/sales\/aesch-4147-e8dd-n9q8\/"},"modified":"2026-07-08T16:02:11","modified_gmt":"2026-07-08T16:02:11","slug":"aesch-4147-e8dd-n9q8","status":"publish","type":"listing","link":"https:\/\/newtak.ch\/en\/sales\/aesch-4147-e8dd-n9q8\/","title":{"rendered":"Charmante 4.5-Zimmer-Maisonettewohnung mit grossz\u00fcgigem Wohnbereich an zentraler Lage"},"content":{"rendered":"<p>Diese sehr sch\u00f6ne Wohnung befindet sich im 1. Stock und ist bequem \u00fcber das Treppenhaus erreichbar. Der Eingangsbereich bietet gen\u00fcgend Platz und verf\u00fcgt \u00fcber eine Freisprechanlage. Auf der rechten Seite befindet sich ein grosses Zimmer, welches sich sehr gut als Schlafzimmer eignet. Das Badezimmer befindet sich in der Mitte des Flurs und ist mit einem Waschbecken, WC und einer Badewanne ausgestattet. Unter der Treppe gibt es sehr viel Platz, welcher zus\u00e4tzlich als Garderobe genutzt werden kann. Auf der linken Seite befindet sich ein Zimmer, welches sich optimal als weiteres Schlafzimmer sowie auch als B\u00fcro eignet. \u00dcber eine breite Steintreppe gelangen Sie zum grossen Wohnessbereich und zur K\u00fcche. Der Wohnbereich l\u00e4sst sich durch seine Gr\u00f6sse individuell gestalten und bietet mit der Deckenh\u00f6he ein angenehmes Raumgef\u00fchl. Die K\u00fcche bietet viel Stauraum und ist mit einer Geschirrsp\u00fclmaschine, einem Backofen, einem Keramikkochfeld und einem K\u00fchlschrank ausgestattet.<\/p>\n<p>Diese Wohnung zeichnet sich durch folgende Merkmale aus:<\/p>\n<ul>\n<li>grossz\u00fcgig auf zwei Etagen<\/li>\n<li>grosser Wohnbereich<\/li>\n<li>sehr gepflegt<\/li>\n<li>ein Aussenparkplatz exkl. CHF 20'000.-<\/li>\n<li>zwei G\u00e4rten zur Mitbenutzung<\/li>\n<li>Hobbyraum inkl.<\/li>\n<li>Velokeller zur Mitbenutzung<\/li>\n<li>Waschk\u00fcche<\/li>\n<li>sehr zentraler Standort<\/li>\n<li>sehr gut erschlossen<\/li>\n<\/ul>\n<p>Haben wir Ihr Interesse geweckt? So vereinbaren Sie noch heute einen Besichtigungstermin.<\/p>\n","protected":false},"featured_media":0,"template":"","listing_type":[2],"property_type":[16],"no_of_rooms":[4],"feature":[300,24],"orientation":[],"locality":[224,218],"postcode":[225],"country":[9],"listing_status":[128],"ra_feature":[11],"class_list":["post-1945","listing","type-listing","status-publish","hentry","listing_type-buy","property_type-apartment","no_of_rooms-6-rooms","feature-child-friendly","feature-view","locality-aesch","locality-basel-landschaft","postcode-225","country-ch","listing_status-sold","ra_feature-published-on-ra"],"acf":[],"_links":{"self":[{"href":"https:\/\/newtak.ch\/en\/wp-json\/wp\/v2\/listing\/1945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newtak.ch\/en\/wp-json\/wp\/v2\/listing"}],"about":[{"href":"https:\/\/newtak.ch\/en\/wp-json\/wp\/v2\/types\/listing"}],"wp:attachment":[{"href":"https:\/\/newtak.ch\/en\/wp-json\/wp\/v2\/media?parent=1945"}],"wp:term":[{"taxonomy":"listing_type","embeddable":true,"href":"https:\/\/newtak.ch\/en\/wp-json\/wp\/v2\/listing_type?post=1945"},{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/newtak.ch\/en\/wp-json\/wp\/v2\/property_type?post=1945"},{"taxonomy":"no_of_rooms","embeddable":true,"href":"https:\/\/newtak.ch\/en\/wp-json\/wp\/v2\/no_of_rooms?post=1945"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/newtak.ch\/en\/wp-json\/wp\/v2\/feature?post=1945"},{"taxonomy":"orientation","embeddable":true,"href":"https:\/\/newtak.ch\/en\/wp-json\/wp\/v2\/orientation?post=1945"},{"taxonomy":"locality","embeddable":true,"href":"https:\/\/newtak.ch\/en\/wp-json\/wp\/v2\/locality?post=1945"},{"taxonomy":"postcode","embeddable":true,"href":"https:\/\/newtak.ch\/en\/wp-json\/wp\/v2\/postcode?post=1945"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/newtak.ch\/en\/wp-json\/wp\/v2\/country?post=1945"},{"taxonomy":"listing_status","embeddable":true,"href":"https:\/\/newtak.ch\/en\/wp-json\/wp\/v2\/listing_status?post=1945"},{"taxonomy":"ra_feature","embeddable":true,"href":"https:\/\/newtak.ch\/en\/wp-json\/wp\/v2\/ra_feature?post=1945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}